{"id":8871,"date":"2023-04-11T05:24:12","date_gmt":"2023-04-11T09:24:12","guid":{"rendered":"https:\/\/ascendleadership.ca\/partners\/"},"modified":"2025-12-11T05:40:35","modified_gmt":"2025-12-11T10:40:35","slug":"partenaires","status":"publish","type":"page","link":"https:\/\/ascendleadership.ca\/fr\/page\/partenaires\/","title":{"rendered":"Partenaires d\u2019Ascend"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8871\" class=\"elementor elementor-8871 elementor-4206\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d935529 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d935529\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b415f10\" data-id=\"b415f10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e09c83 elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"1e09c83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n    <div class=\"dsm-wrapper\">\n\n        \n            <div class=\"dsm-row\">\n\n                <!-- LEFT SIDE LABEL + DIVIDER -->\n                <div class=\"dsm-left\">\n                    <div class=\"dsm-category\">\n                        PLATINUM \/<br \/>\n PLATINE                    <\/div>\n                    <div class=\"dsm-divider\"><\/div>\n                <\/div>\n\n                <!-- RIGHT SIDE LOGOS -->\n                <div class=\"dsm-right\">\n                    <div class=\"dsm-logos\">\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.accenture.com\/ca-en\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/08\/Accenture_Logo_Black_Purple-300x79.png\"\n                                            alt=\"Accenture\"\n                                            title=\"Accenture\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.bmo.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/BMO-01-300x130.png\"\n                                            alt=\"BMO\"\n                                            title=\"BMO\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.cibc.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/CIBC_logo_rgb_4-cm-300x77.png\"\n                                            alt=\"CIBC\"\n                                            title=\"CIBC\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www2.deloitte.com\/ca\/en.html?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/deloitte-01-300x150.png\"\n                                            alt=\"Deloitte\"\n                                            title=\"Deloitte\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.ey.com\/en_ca?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2026\/07\/EY-logo-small-294x300.png\"\n                                            alt=\"EY\"\n                                            title=\"EY\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.home.kpmg\/ca\/en\/home.html?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/KPMG_logo-01-300x146.png\"\n                                            alt=\"KPMG\"\n                                            title=\"KPMG\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.manulife.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/manulife-01-300x107.png\"\n                                            alt=\"Manulife\"\n                                            title=\"Manulife\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.pwc.com\/ca\/en\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/PwC_logo_rgb_colour_pos-300x193.png\"\n                                            alt=\"PwC\"\n                                            title=\"PwC\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.rbc.com\/diversity?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/rbc-01-263x300.png\"\n                                            alt=\"RBC\"\n                                            title=\"RBC\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.scotiabank.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/Scotiabank-Logo-2026-300x56.png\"\n                                            alt=\"Scotiabank\"\n                                            title=\"Scotiabank\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.sunlife.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/SL_CLR_RGB-2-600x145-2-300x73.png\"\n                                            alt=\"Sun Life\"\n                                            title=\"Sun Life\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.td.com\/ca\/en\/personal-banking\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/tc-01-400x400-1-300x300.png\"\n                                            alt=\"TD\"\n                                            title=\"TD\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"dsm-row\">\n\n                <!-- LEFT SIDE LABEL + DIVIDER -->\n                <div class=\"dsm-left\">\n                    <div class=\"dsm-category\">\n                        GOLD \/<br \/>\n OR                    <\/div>\n                    <div class=\"dsm-divider\"><\/div>\n                <\/div>\n\n                <!-- RIGHT SIDE LOGOS -->\n                <div class=\"dsm-right\">\n                    <div class=\"dsm-logos\">\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.aircanada.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2024\/06\/AirCanada_logo-300x48.jpg\"\n                                            alt=\"Air Canada\"\n                                            title=\"Air Canada\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"dsm-row\">\n\n                <!-- LEFT SIDE LABEL + DIVIDER -->\n                <div class=\"dsm-left\">\n                    <div class=\"dsm-category\">\n                        SILVER \/<br \/>\n ARGENT                    <\/div>\n                    <div class=\"dsm-divider\"><\/div>\n                <\/div>\n\n                <!-- RIGHT SIDE LOGOS -->\n                <div class=\"dsm-right\">\n                    <div class=\"dsm-logos\">\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.bdc.ca\/en?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/BDC_Logo_Horiz-01-300x182.png\"\n                                            alt=\"BDC\"\n                                            title=\"BDC\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.bell.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/Bell-300x207.png\"\n                                            alt=\"Bell\"\n                                            title=\"Bell\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.cadillacfairview.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/CF-01-417x400-1-300x288.png\"\n                                            alt=\"Cadillac Fairview\"\n                                            title=\"Cadillac Fairview\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"dsm-row\">\n\n                <!-- LEFT SIDE LABEL + DIVIDER -->\n                <div class=\"dsm-left\">\n                    <div class=\"dsm-category\">\n                        BRONZE \/<br \/>\n BRONZE                    <\/div>\n                    <div class=\"dsm-divider\"><\/div>\n                <\/div>\n\n                <!-- RIGHT SIDE LOGOS -->\n                <div class=\"dsm-right\">\n                    <div class=\"dsm-logos\">\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.canadalife.com\/\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/CanadaLife_E_TM_rgb-300x164.jpg\"\n                                            alt=\"Canada Life\"\n                                            title=\"Canada Life\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/cassels.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/cassels-01-300x116.png\"\n                                            alt=\"Cassels\"\n                                            title=\"Cassels\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.fasken.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/fasken-01-300x116.png\"\n                                            alt=\"Fasken\"\n                                            title=\"Fasken\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.igmfinancial.com\/en?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/11\/IGM-companies-lockup-2020-horizontal-v2-1-600x196-1-300x98.jpg\"\n                                            alt=\"IGM Financial\"\n                                            title=\"IGM Financial\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.kyndryl.com\/ca\/en\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/07\/Kyndryl-Logo-300x96.png\"\n                                            alt=\"Kyndryl\"\n                                            title=\"Kyndryl\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.loblaw.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/loblaw-01-300x179.png\"\n                                            alt=\"Loblaw Companies Limited\"\n                                            title=\"Loblaw Companies Limited\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.mawer.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/10\/Mawer-Logo-300x57.png\"\n                                            alt=\"Mawer\"\n                                            title=\"Mawer\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.microsoft.com\/en-ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/Microsoft-Transparent-Logo-300x110.png\"\n                                            alt=\"Microsoft\"\n                                            title=\"Microsoft\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.omers.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/05\/Omers-Logo-300x69.png\"\n                                            alt=\"OMERS\"\n                                            title=\"OMERS\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.osc.gov.on.ca\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2024\/06\/osc-logo-colour-en-JPG-opt-test-300x150.jpg\"\n                                            alt=\"Ontario Securities Commission\"\n                                            title=\"Ontario Securities Commission\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.osler.com\/?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2024\/06\/Osler_logo.jpg\"\n                                            alt=\"Osler\"\n                                            title=\"Osler\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/rsmcanada.com\/\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2023\/04\/RSM-01-300x139.png\"\n                                            alt=\"RSM Canada\"\n                                            title=\"RSM Canada\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.spglobal.com\/en?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/12\/SPGI-Positive-Digital-Logo_Large-PNG-300x116.png\"\n                                            alt=\"S&#038;P Global\"\n                                            title=\"S&#038;P Global\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                            <div class=\"dsm-logo-wrap\">\n                                <a href=\"https:\/\/www.torys.com\/en?utm_source=ascendcanada&#038;utm_medium=ascendcanada&#038;utm_campaign=sponsorship&#038;utm_content=logo\" target=\"_blank\">\n                                    <div class=\"dsm-logo-circle\">\n                                        <img decoding=\"async\"\n                                            src=\"https:\/\/ascendleadership.ca\/wp-content\/uploads\/2025\/05\/Torys-Logo-300x77.png\"\n                                            alt=\"Torys\"\n                                            title=\"Torys\" \/>\n                                    <\/div>\n\n                                                                        <\/a>                            <\/div>\n\n                        \n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n    <\/div>\n\n                                                    <style>\n                                                    .dsm-wrapper {\n                                                        width: 100%;\n                                                        margin: 40px auto;\n                                                    }\n\n                                                    .dsm-row {\n                                                        display: flex;\n                                                        padding: 40px 0;\n                                                        border-bottom: 1px solid #eee;\n                                                        gap: 20px;\n                                                        position: relative;\n                                                    }\n\n                                                    \/* LEFT COLUMN *\/\n                                                    .dsm-left {\n                                                        width: 150px;\n                                                        padding-right: 5px;\n                                                        position: relative;\n                                                        text-align: right;\n                                                    }\n\n                                                    .dsm-category {\n                                                        display: flex;\n                                                        flex-direction: column;\n                                                        justify-content: center;\n                                                        \/* Centers text vertically *\/\n                                                        align-items: center;\n                                                        \/* Centers text horizontally *\/\n                                                        height: 100%;\n                                                        \/* Take full height of left column *\/\n                                                        font-size: 15px;\n                                                        color: #f28c1d;\n                                                        font-weight: 600;\n                                                        border-right: 2px solid;\n                                                        position: relative;\n                                                    }\n\n                                                    \/* RIGHT SIDE LOGOS *\/\n                                                    .dsm-right {\n                                                        flex: 1;\n                                                    }\n\n                                                    .dsm-logos {\n                                                        display: flex;\n                                                        gap: 15px;\n                                                        flex-wrap: wrap;\n                                                        align-items: center;\n                                                        margin-left: 5px;\n                                                    }\n\n                                                    .dsm-logo-circle {\n                                                        width: 130px;\n                                                        justify-content: center;\n                                                        align-items: center;\n                                                    }\n\n                                                    .dsm-logo-circle img {\n                                                        max-width: 90%;\n                                                        object-fit: contain;\n                                                        transition: 0.3s;\n                                                    }\n\n                                                    .dsm-logo-circle:hover img {\n                                                        transform: scale(1.06);\n                                                    }\n\n                                                    .dsm-category::before,\n                                                    .dsm-category::after {\n                                                        content: \"\";\n                                                        width: 8px;\n                                                        height: 8px;\n                                                        border-radius: 50%;\n                                                        background-color: #f28c1d;\n                                                        position: absolute;\n                                                        right: -5px;\n                                                    }\n\n                                                    .dsm-category::before {\n                                                        top: -8px;\n                                                    }\n\n                                                    .dsm-category::after {\n                                                        bottom: -8px;\n                                                    }\n\n                                                    \/* RESPONSIVE STYLES *\/\n                                                    @media (max-width: 768px) {\n                                                        .dsm-category {\n                                                            border-bottom: 2px solid;\n                                                            border-right: none;\n                                                            padding-bottom: 20px;\n                                                        }\n\n                                                        .dsm-category::before {\n                                                            bottom: -5px;\n                                                            right: -8px;\n                                                            top: unset;\n                                                        }\n\n                                                        .dsm-category::after {\n                                                            bottom: -5px;\n                                                            left: -8px;\n                                                            right: unset;\n                                                        }\n\n                                                        .dsm-row {\n                                                            flex-direction: column;\n                                                            align-items: center;\n                                                        }\n\n                                                        .dsm-left {\n                                                            width: 100%;\n                                                            text-align: center;\n                                                            padding: 0;\n                                                            position: relative;\n                                                        }\n\n                                                        .dsm-logos {\n                                                            justify-content: center;\n                                                        }\n                                                    }\n                                                <\/style>\n\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":9980,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/template-full-width.php","meta":{"footnotes":""},"class_list":["post-8871","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/pages\/8871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/comments?post=8871"}],"version-history":[{"count":84,"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/pages\/8871\/revisions"}],"predecessor-version":[{"id":17467,"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/pages\/8871\/revisions\/17467"}],"up":[{"embeddable":true,"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/pages\/9980"}],"wp:attachment":[{"href":"https:\/\/ascendleadership.ca\/fr\/wp-json\/wp\/v2\/media?parent=8871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}